{"id":21,"date":"2025-11-29T18:07:43","date_gmt":"2025-11-29T18:07:43","guid":{"rendered":"https:\/\/www.carlaentrepagines.com\/wordpress\/?page_id=21"},"modified":"2025-11-29T20:17:48","modified_gmt":"2025-11-29T20:17:48","slug":"autores","status":"publish","type":"page","link":"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/","title":{"rendered":"Autores"},"content":{"rendered":"\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-152 fitxa-autora type-fitxa-autora status-publish hentry\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h2 class=\"wp-block-post-title\"><a href=\"https:\/\/www.carlaentrepagines.com\/wordpress\/fitxa-autora\/dolores-redondo\/\" target=\"_self\" >Dolores Redondo<\/a><\/h2><\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-151 fitxa-autora type-fitxa-autora status-publish hentry\">\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\"><h2 class=\"wp-block-post-title\"><a href=\"https:\/\/www.carlaentrepagines.com\/wordpress\/fitxa-autora\/marina-martori\/\" target=\"_self\" >Marina Martori<\/a><\/h2><\/div>\n<\/div>\n\n<\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-21","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Autores - carlaentrepagines<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autores - carlaentrepagines\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/\" \/>\n<meta property=\"og:site_name\" content=\"carlaentrepagines\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T20:17:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/\",\"url\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/\",\"name\":\"Autores - carlaentrepagines\",\"isPartOf\":{\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/#website\"},\"datePublished\":\"2025-11-29T18:07:43+00:00\",\"dateModified\":\"2025-11-29T20:17:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/#website\",\"url\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/\",\"name\":\"carlaentrepagines\",\"description\":\"My WordPress Blog\",\"publisher\":{\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/9fe1556785edf9dc3371ca98092baf28\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/9fe1556785edf9dc3371ca98092baf28\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-content\/uploads\/2025\/11\/file_00000000f95c6243ac87eda4988a913c.png\",\"contentUrl\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-content\/uploads\/2025\/11\/file_00000000f95c6243ac87eda4988a913c.png\",\"width\":1024,\"height\":1024,\"caption\":\"admin\"},\"logo\":{\"@id\":\"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/www.carlaentrepagines.com\/wordpress\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autores - carlaentrepagines","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/","og_locale":"ca_ES","og_type":"article","og_title":"Autores - carlaentrepagines","og_url":"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/","og_site_name":"carlaentrepagines","article_modified_time":"2025-11-29T20:17:48+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/","url":"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/","name":"Autores - carlaentrepagines","isPartOf":{"@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/#website"},"datePublished":"2025-11-29T18:07:43+00:00","dateModified":"2025-11-29T20:17:48+00:00","breadcrumb":{"@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/autores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.carlaentrepagines.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Autores"}]},{"@type":"WebSite","@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/#website","url":"https:\/\/www.carlaentrepagines.com\/wordpress\/","name":"carlaentrepagines","description":"My WordPress Blog","publisher":{"@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/9fe1556785edf9dc3371ca98092baf28"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlaentrepagines.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":["Person","Organization"],"@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/9fe1556785edf9dc3371ca98092baf28","name":"admin","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/image\/","url":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-content\/uploads\/2025\/11\/file_00000000f95c6243ac87eda4988a913c.png","contentUrl":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-content\/uploads\/2025\/11\/file_00000000f95c6243ac87eda4988a913c.png","width":1024,"height":1024,"caption":"admin"},"logo":{"@id":"https:\/\/www.carlaentrepagines.com\/wordpress\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/www.carlaentrepagines.com\/wordpress"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/www.carlaentrepagines.com\/wordpress\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":null,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":2,"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":150,"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/pages\/21\/revisions\/150"}],"wp:attachment":[{"href":"https:\/\/www.carlaentrepagines.com\/wordpress\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}